{"id":25084,"date":"2021-06-28T13:52:49","date_gmt":"2021-06-28T13:52:49","guid":{"rendered":"https:\/\/tahecosmetics.com\/professional\/home\/"},"modified":"2026-04-09T12:42:50","modified_gmt":"2026-04-09T12:42:50","slug":"home","status":"publish","type":"page","link":"https:\/\/tahecosmetics.com\/professional\/pt\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25084\" class=\"elementor elementor-25084\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e7d7894 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7e7d7894\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-681436a\" data-id=\"681436a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81498f3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"81498f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tahe, tu marca profesional de peluquer\u00eda  <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44154f68\" data-id=\"44154f68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-200f4ac elementor-invisible elementor-widget elementor-widget-image\" data-id=\"200f4ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"408\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg\" class=\"attachment-full size-full wp-image-14446\" alt=\"marca profesional peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg 800w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada-600x306.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada-300x153.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada-768x392.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada-580x296.jpg 580w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23c421e elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"23c421e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7e9718\" data-id=\"f7e9718\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d2107c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d2107c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-13d1c67 elementor-hidden-tablet\" data-id=\"13d1c67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-77123bc\" data-id=\"77123bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1d1fcf elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b1d1fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Crecemos contigo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-af9a3b8 elementor-hidden-tablet\" data-id=\"af9a3b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db5d296 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db5d296\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b5971ce elementor-hidden-tablet\" data-id=\"b5971ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-16c80cf\" data-id=\"16c80cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbd820b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fbd820b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Somos una marca l\u00edder en fabricaci\u00f3n y distribuci\u00f3n de productos para el sector profesional de peluquer\u00eda y est\u00e9tica.<\/p><p>Para nosotros, lo m\u00e1s importante son nuestros clientes. Por eso, todas nuestras f\u00f3rmulas est\u00e1n exclusivamente pensadas para cuidar su salud y su belleza integral.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fc96cc2 elementor-hidden-tablet\" data-id=\"fc96cc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84ca707 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"84ca707\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ef73ba\" data-id=\"7ef73ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0edaa5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0edaa5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bebe915 elementor-hidden-tablet\" data-id=\"bebe915\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-03bf085\" data-id=\"03bf085\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44d4b7f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"44d4b7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfTe gustar\u00eda hacer crecer tu sal\u00f3n?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3854260 elementor-hidden-tablet\" data-id=\"3854260\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb0d0e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb0d0e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-63169cb elementor-hidden-tablet\" data-id=\"63169cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7c56542\" data-id=\"7c56542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3e12c9 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c3e12c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: #ffffff; letter-spacing: 0px;\">D\u00e9janos ayudarte a <\/span>convertir tu sal\u00f3n en un negocio m\u00e1s rentable.<\/p><p><span style=\"color: #993366;\"><strong>\u00a1Asesoramiento 100% GRATUITO!<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65c01ae elementor-widget elementor-widget-button\" data-id=\"65c01ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/tahecosmetics.com\/professional\/de-estilista-a-negocio-rentable\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reinventa tu sal\u00f3n desde cero  &gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55a3f4e elementor-hidden-tablet\" data-id=\"55a3f4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7781a1c3 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"7781a1c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-301fb6fd\" data-id=\"301fb6fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9d30cc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9d30cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce3556d\" data-id=\"ce3556d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5534a2f e-transform elementor-widget elementor-widget-image\" data-id=\"5534a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2379\" height=\"1094\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse.jpg\" class=\"attachment-full size-full wp-image-24958\" alt=\"\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse.jpg 2379w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-300x138.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-1024x471.jpg 1024w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-768x353.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-1536x706.jpg 1536w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-2048x942.jpg 2048w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-580x267.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-860x395.jpg 860w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-1160x533.jpg 1160w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/10\/coleccion-glympse-600x276.jpg 600w\" sizes=\"(max-width: 2379px) 100vw, 2379px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f13e10e\" data-id=\"f13e10e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfef25f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dfef25f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colecciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06e41a2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"06e41a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">Descubre GLYMPSE: libertad, modernidad y un estilo vibrante \u00fanico<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d2901 elementor-widget elementor-widget-button\" data-id=\"26d2901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/tahecosmetics.com\/professional\/coleccion\/glympse\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver colecci\u00f3n   &gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90ed714 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90ed714\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-001e4c1\" data-id=\"001e4c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6128b98 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"6128b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"496\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering.jpg\" class=\"attachment-full size-full wp-image-21889\" alt=\"\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-600x331.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-300x165.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-768x423.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-580x320.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-860x474.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2a1866 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a2a1866\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubre Tahe Marketing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeb8f40 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"eeb8f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">La plataforma de recursos digitales para profesionales de Tahe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-679486a elementor-widget elementor-widget-spacer\" data-id=\"679486a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ccb393 elementor-widget elementor-widget-button\" data-id=\"7ccb393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/marketing.tahecosmetics.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visita la plataforma &gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4fcd53d\" data-id=\"4fcd53d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99df2fe elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"99df2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"496\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering.jpg\" class=\"attachment-full size-full wp-image-21889\" alt=\"\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-600x331.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-300x165.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-768x423.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-580x320.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2024\/04\/banner-markering-860x474.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b169cdb elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b169cdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-39a55dbc\" data-id=\"39a55dbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a93dac elementor-widget elementor-widget-image\" data-id=\"1a93dac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"259\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1.png\" class=\"attachment-full size-full wp-image-14625\" alt=\"productos profesionales peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1.png 800w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1-600x194.png 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1-300x97.png 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1-768x249.png 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/MAGIC-RIZOS-LOW-POO-1-580x188.png 580w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3f7fee48\" data-id=\"3f7fee48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2025e9d7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2025e9d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tahe es s\u00edmbolo de ilusi\u00f3n, visi\u00f3n y car\u00e1cter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ddd0ccc\" data-id=\"ddd0ccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57745c6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57745c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f2a987\" data-id=\"5f2a987\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b7a5f2 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"9b7a5f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"496\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe.jpg\" class=\"attachment-full size-full wp-image-14467\" alt=\"marca peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-600x331.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-300x165.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-768x423.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-580x320.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-860x474.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12f81fa elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"12f81fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estamos presentes en m\u00e1s de 55 pa\u00edses<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7898f1e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7898f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">Somos una marca internacional y vers\u00e1til, adapt\u00e1ndonos a los mercados m\u00e1s exigentes.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4889d24 elementor-widget elementor-widget-spacer\" data-id=\"4889d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25dc122 elementor-widget elementor-widget-button\" data-id=\"25dc122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfNos conocemos? &gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c895a74\" data-id=\"c895a74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b111f2b elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"b111f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"496\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe.jpg\" class=\"attachment-full size-full wp-image-14467\" alt=\"marca peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-600x331.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-300x165.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-768x423.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-580x320.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/lumiere_coleccion_glam_fest_poster_tahe-860x474.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4983fc0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4983fc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eebb258\" data-id=\"eebb258\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3793ed2 elementor-widget elementor-widget-image\" data-id=\"3793ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"556\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04.jpg\" class=\"attachment-full size-full wp-image-14618\" alt=\"salones profesionales peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04.jpg 1200w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-600x278.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-300x139.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-1024x474.jpg 1024w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-768x356.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-580x269.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-860x398.jpg 860w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-04-1160x537.jpg 1160w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-392b1fc\" data-id=\"392b1fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b6f666 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3b6f666\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos adaptamos a tu negocio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfa7ddb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dfa7ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">Te ofrecemos soluciones profesionales espec\u00edficas para tu sal\u00f3n.  <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f00e642 elementor-widget elementor-widget-spacer\" data-id=\"f00e642\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d8f4c elementor-widget elementor-widget-button\" data-id=\"48d8f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Te contamos los detalles   &gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2652732 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2652732\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-110d475\" data-id=\"110d475\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9975113 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"9975113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"531\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca.jpg\" class=\"attachment-full size-full wp-image-14444\" alt=\"peluqueros profesionales\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-600x354.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-300x177.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-768x453.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-580x342.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-860x507.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46897ce elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"46897ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Muy cerca de ti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a42409 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1a42409\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">Contamos con una red de profesionales en todo el territorio nacional.  <br><br> Adem\u00e1s, ofrecemos m\u00e1s de 250 formaciones de distintos \u00e1mbitos.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df4b1f0 elementor-widget elementor-widget-spacer\" data-id=\"df4b1f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f6a243 elementor-widget elementor-widget-button\" data-id=\"4f6a243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quiero una visita &gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3202688\" data-id=\"3202688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb2b08d elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"bb2b08d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"531\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca.jpg\" class=\"attachment-full size-full wp-image-14444\" alt=\"peluqueros profesionales\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-600x354.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-300x177.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-768x453.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-580x342.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-mas-cerca-860x507.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-557c5dd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"557c5dd\" data-element_type=\"section\" data-e-type=\"section\" id=\"beneficios\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9eb43a\" data-id=\"c9eb43a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0a3387 elementor-widget elementor-widget-image\" data-id=\"a0a3387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"419\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3.jpg\" class=\"attachment-full size-full wp-image-14640\" alt=\"formaci\u00f3n profesionales peluquer\u00eda\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3-600x279.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3-300x140.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3-768x358.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3-580x270.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-formacion-home-3-860x400.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9fb407e\" data-id=\"9fb407e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05bece7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"05bece7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n para profesionales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d82e9c8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d82e9c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-xxl\">Siempre es buen momento para seguir form\u00e1ndote. Te ofrecemos m\u00e1s de 250 cursos al a\u00f1o en los distintos \u00e1mbitos: t\u00e9cnicos, art\u00edsticos, de gesti\u00f3n y motivaci\u00f3n y c\u00f3mo optimizar tu negocio con Rentahe. \n<br><br>\nInf\u00f3rmate de los cursos m\u00e1s pr\u00f3ximos a tu zona.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a21a0 elementor-widget elementor-widget-spacer\" data-id=\"d9a21a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1023e42 elementor-widget elementor-widget-button\" data-id=\"1023e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quiero m\u00e1s info &gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8add326 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"8add326\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa5158b\" data-id=\"fa5158b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fe2b151 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe2b151\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-95c4972\" data-id=\"95c4972\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e07d411 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"e07d411\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"502\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028.jpg\" class=\"attachment-large size-large wp-image-14495\" alt=\"asesoramiento peluqueros\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-600x335.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-300x167.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-768x428.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-580x324.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-860x480.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e61ea elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"26e61ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Te guiamos<br> Avanzamos juntos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a749c6c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a749c6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Queremos que conozcas a fondo todos nuestros productos y su funcionamiento. Ent\u00e9rate de todas nuestras novedades, sac\u00e1ndole el m\u00e1ximo partido a cada una de nuestras l\u00edneas. Contacta con nosotros para cualquier duda, nos encantar\u00e1 guiarte.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0990ec elementor-widget elementor-widget-spacer\" data-id=\"e0990ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47ed520 elementor-widget elementor-widget-button\" data-id=\"47ed520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quiero asesoramiento  &gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca9590d\" data-id=\"ca9590d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-306f857 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"306f857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"502\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028.jpg\" class=\"attachment-large size-large wp-image-14495\" alt=\"asesoramiento peluqueros\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-600x335.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-300x167.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-768x428.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-580x324.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/AF-TAHE11028-860x480.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ee46ac elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2ee46ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5567e1\" data-id=\"f5567e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2271cd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2271cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fbfa57e\" data-id=\"fbfa57e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34e395d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"34e395d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si eres profesional, \u00a1\u00fanete nuestra newsletter!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29eeb1c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"29eeb1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Suscr\u00edbete a nuestra Newsletter\u00a0y recibe todas las novedades de Tahe, los pr\u00f3ximos lanzamientos, informaci\u00f3n sobre tendencias, consejos de belleza y cuidado personal.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d062779 elementor-widget elementor-widget-spacer\" data-id=\"d062779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a534419 elementor-widget elementor-widget-shortcode\" data-id=\"a534419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Contact form not found.<\/p><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-924d5ac elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"924d5ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a40c4ca\" data-id=\"a40c4ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98884f5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98884f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c3d7f1f\" data-id=\"c3d7f1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ca4c5 elementor-widget elementor-widget-image\" data-id=\"77ca4c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03.jpg\" class=\"attachment-full size-full wp-image-14431\" alt=\"salones organic care\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03.jpg 800w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03-600x400.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03-300x200.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03-768x512.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-profesioanles-salones-03-580x386.jpg 580w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bfcaf01\" data-id=\"bfcaf01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b994d6e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b994d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El mundo organic te est\u00e1 esperando<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc23db7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bc23db7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nuestros Salones Organic son mucho m\u00e1s que un sal\u00f3n de peluquer\u00eda. Son ventajas y rentabilidad mientras cuidas de tus clientes y del medio ambiente. Descubre c\u00f3mo conseguir un menor impacto medioambiental. <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695e9cd elementor-widget elementor-widget-spacer\" data-id=\"695e9cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce911d elementor-widget elementor-widget-button\" data-id=\"3ce911d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quiero un sal\u00f3n sostenible  &gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0088806 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"0088806\" data-element_type=\"section\" data-e-type=\"section\" id=\"rentahe\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7faeffa\" data-id=\"7faeffa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35e84e9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35e84e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b1375c3\" data-id=\"b1375c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5173313 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"5173313\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"399\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01.jpg\" class=\"attachment-large size-large wp-image-14741\" alt=\"RenTahe\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01.jpg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01-600x266.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01-300x133.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01-768x340.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01-580x257.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-rentahe-01-860x381.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e2b97b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3e2b97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rentabilidad para tu sal\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c93a9e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7c93a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Te ofrecemos un servicio exclusivo de alquiler de aparatolog\u00eda est\u00e9tica para la realizaci\u00f3n de distintos tratamientos, aumentando tu rentabilidad y expandiendo tu negocio.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a2346 elementor-widget elementor-widget-spacer\" data-id=\"d2a2346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddfba0b elementor-widget elementor-widget-button\" data-id=\"ddfba0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conoce RenTahe  &gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f84c276\" data-id=\"f84c276\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc08598 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"fc08598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"399\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown.jpeg\" class=\"attachment-large size-large wp-image-19917\" alt=\"\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown.jpeg 900w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown-600x266.jpeg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown-300x133.jpeg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown-768x340.jpeg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown-580x257.jpeg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2023\/04\/Unknown-860x381.jpeg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a78638 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"0a78638\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;viewport&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ac7b7a\" data-id=\"1ac7b7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc8021d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc8021d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-370cf9a\" data-id=\"370cf9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-127eefb elementor-widget elementor-widget-image\" data-id=\"127eefb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1175\" height=\"523\" src=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2.jpg\" class=\"attachment-full size-full wp-image-14712\" alt=\"soporte para profesionales\" srcset=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2.jpg 1175w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-600x267.jpg 600w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-300x134.jpg 300w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-1024x456.jpg 1024w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-768x342.jpg 768w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-580x258.jpg 580w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-860x383.jpg 860w, https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tarhe-soporte2-1160x516.jpg 1160w\" sizes=\"(max-width: 1175px) 100vw, 1175px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-75a03ca\" data-id=\"75a03ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d110756 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d110756\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tenemos la soluci\u00f3n que necesitas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec04109 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ec04109\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00bfTienes una incidencia? Nuestro equipo de profesionales te ayudar\u00e1 lo m\u00e1s r\u00e1pido posible con cualquier problema que te haya podido surgir.  <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75bb749 elementor-widget elementor-widget-spacer\" data-id=\"75bb749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9db20 elementor-widget elementor-widget-button\" data-id=\"9e9db20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cu\u00e9ntanos tu incidencia   &gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d03cacc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d03cacc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-510b419\" data-id=\"510b419\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed6275c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ed6275c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lo que dicen nuestros profesionales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-df134ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df134ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6688b67\" data-id=\"6688b67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0dab12 elementor-widget elementor-widget-video\" data-id=\"c0dab12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/566943455?color=000000&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3285af1\" data-id=\"3285af1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f99c28 elementor-widget elementor-widget-video\" data-id=\"5f99c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/566943420?color=000000&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-219c116 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219c116\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-692472a\" data-id=\"692472a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e0b9d elementor-widget elementor-widget-video\" data-id=\"a7e0b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/729646581?color=000000&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2752c5d\" data-id=\"2752c5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80ac640 elementor-widget elementor-widget-video\" data-id=\"80ac640\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/647383612?color=000000&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3561d73 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3561d73\" data-element_type=\"section\" data-e-type=\"section\" id=\"contacto\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc82bfd\" data-id=\"fc82bfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2549d5d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2549d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfEn qu\u00e9 podemos ayudarte? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7a7e2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a7e2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-99f0a81\" data-id=\"99f0a81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-971d0b7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"971d0b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f14152-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"14152\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/professional\/pt\/wp-json\/wp\/v2\/pages\/25084#wpcf7-f14152-o1\" method=\"post\" class=\"wpcf7-form init e87a6a1b3e6d cmatic-conn cmatic-aud-15 cmatic-mapd0-0 cmatic-098109 cmatic-sent-0 cmatic-total-0\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"14152\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f14152-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<style>\n.fomn2 p, .fomn22 p {\n padding: 0px;\n}\n<\/style>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre y apellidos\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-739\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-739\"><option value=\"\u00bfQu\u00e9 buscas?\">\u00bfQu\u00e9 buscas?<\/option><option value=\"Quiero ser distribuidor\">Quiero ser distribuidor<\/option><option value=\"Busco distribuidor\">Busco distribuidor<\/option><option value=\"Soy profesional\">Soy profesional<\/option><\/select><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ciudad\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Ciudad\" value=\"\" type=\"text\" name=\"ciudad\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn2\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"pais\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Pa\u00eds\" value=\"\" type=\"text\" name=\"pais\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fomn22\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Observaciones\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<p><span style=\"font-size: 10px; line-height: 12px !important; display: block;\">Se informa al interesado que sus datos personales van a ser incorporados a un fichero automatizado, cuyo responsable es TAHE PRODUCTOS COSM\u00c9TICOS S.L. Estos datos son absolutamente necesarios para poder ofrecer un servicio de calidad y garant\u00edas. El titular de los datos consiente su comunicaci\u00f3n a otras empresas de nuestro grupo, para procurarle la prestaci\u00f3n contratada\/ solicitada. En cumplimiento de la Ley Org\u00e1nica 15\/1999 de 13 de Diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal, y del Real Decreto 1720\/2007, de 21 de Diciembre, Reglamento de desarrollo de la Ley Org\u00e1nica 15\/1999, el TAHE PRODUCTOS COSM\u00c9TICOS S.L., propietario y titular de esta base de datos, ha adoptado las medidas adecuadas para proteger sus datos de car\u00e1cter personal con el fin de salvaguardar su derecho al honor e intimidad personal y familiar. El interesado podr\u00e1 ejercitar sus derechos de oposici\u00f3n, acceso, rectificaci\u00f3n y cancelaci\u00f3n en relaci\u00f3n sus datos personales dirigi\u00e9ndose por escrito a TAHE PRODUCTOS COSM\u00c9TICOS, en la cual existen a disposici\u00f3n del titular de los datos modelos escritos mediante los cuales ejercitar tales derechos.<\/span>\n<\/p>\n<div style=\"margin-left:5px;\">\n\t<p><span class=\"texto-formulario\"><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-279\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-279\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> He le\u00eddo y acepto el <a target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/tahecosmetics.com\/professional\/aviso-legal\/\">Aviso Legal<\/a> y la <a target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/tahecosmetics.com\/professional\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a>.<\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n\t<\/p>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tahe, tu marca profesional de peluquer\u00eda Crecemos contigo Somos una marca l\u00edder en fabricaci\u00f3n y distribuci\u00f3n de productos para el sector profesional de peluquer\u00eda y est\u00e9tica. Para nosotros, lo m\u00e1s importante son nuestros clientes. Por eso, todas nuestras f\u00f3rmulas est\u00e1n exclusivamente pensadas para cuidar su salud y su belleza integral. \u00bfTe gustar\u00eda hacer crecer tu&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-25084","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La marca que usan los profesionales de peluquer\u00eda | TAHE<\/title>\n<meta name=\"description\" content=\"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tahecosmetics.com\/professional\/pt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La marca que usan los profesionales de peluquer\u00eda | TAHE\" \/>\n<meta property=\"og:description\" content=\"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tahecosmetics.com\/professional\/pt\/\" \/>\n<meta property=\"og:site_name\" content=\"Tahe Profesional\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T12:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/\",\"url\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/\",\"name\":\"La marca que usan los profesionales de peluquer\u00eda | TAHE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tahe_profesionales-portada.jpg\",\"datePublished\":\"2021-06-28T13:52:49+00:00\",\"dateModified\":\"2026-04-09T12:42:50+00:00\",\"description\":\"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tahe_profesionales-portada.jpg\",\"contentUrl\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Tahe_profesionales-portada.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#website\",\"url\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/\",\"name\":\"Tahe Profesional\",\"description\":\"Productos Cosm\u00e9ticos para Profesionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#organization\"},\"alternateName\":\"Tahe Profesional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#organization\",\"name\":\"Tahe Productos Cosm\u00e9ticos, S.L.\",\"url\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/tahe-logo-dark.png\",\"contentUrl\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/tahe-logo-dark.png\",\"width\":800,\"height\":359,\"caption\":\"Tahe Productos Cosm\u00e9ticos, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/tahecosmetics.com\\\/professional\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La marca que usan los profesionales de peluquer\u00eda | TAHE","description":"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tahecosmetics.com\/professional\/pt\/","og_locale":"pt_PT","og_type":"article","og_title":"La marca que usan los profesionales de peluquer\u00eda | TAHE","og_description":"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!","og_url":"https:\/\/tahecosmetics.com\/professional\/pt\/","og_site_name":"Tahe Profesional","article_modified_time":"2026-04-09T12:42:50+00:00","og_image":[{"width":800,"height":408,"url":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tahecosmetics.com\/professional\/pt\/","url":"https:\/\/tahecosmetics.com\/professional\/pt\/","name":"La marca que usan los profesionales de peluquer\u00eda | TAHE","isPartOf":{"@id":"https:\/\/tahecosmetics.com\/professional\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tahecosmetics.com\/professional\/pt\/#primaryimage"},"image":{"@id":"https:\/\/tahecosmetics.com\/professional\/pt\/#primaryimage"},"thumbnailUrl":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg","datePublished":"2021-06-28T13:52:49+00:00","dateModified":"2026-04-09T12:42:50+00:00","description":"\u00bfEres peluquero o peluquera profesional? Descubre Tahe, la marca que usan los profesionales del mundo de la peluquer\u00eda y la est\u00e9tica. \u00a1\u00danete a nosotros!","breadcrumb":{"@id":"https:\/\/tahecosmetics.com\/professional\/pt\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tahecosmetics.com\/professional\/pt\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/tahecosmetics.com\/professional\/pt\/#primaryimage","url":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg","contentUrl":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/Tahe_profesionales-portada.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tahecosmetics.com\/professional\/pt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tahecosmetics.com\/professional\/pt\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/tahecosmetics.com\/professional\/#website","url":"https:\/\/tahecosmetics.com\/professional\/","name":"Tahe Profesional","description":"Productos Cosm\u00e9ticos para Profesionales","publisher":{"@id":"https:\/\/tahecosmetics.com\/professional\/#organization"},"alternateName":"Tahe Profesional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tahecosmetics.com\/professional\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/tahecosmetics.com\/professional\/#organization","name":"Tahe Productos Cosm\u00e9ticos, S.L.","url":"https:\/\/tahecosmetics.com\/professional\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/tahecosmetics.com\/professional\/#\/schema\/logo\/image\/","url":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-logo-dark.png","contentUrl":"https:\/\/tahecosmetics.com\/professional\/wp-content\/uploads\/2021\/06\/tahe-logo-dark.png","width":800,"height":359,"caption":"Tahe Productos Cosm\u00e9ticos, S.L."},"image":{"@id":"https:\/\/tahecosmetics.com\/professional\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/pages\/25084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/comments?post=25084"}],"version-history":[{"count":21,"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/pages\/25084\/revisions"}],"predecessor-version":[{"id":55738,"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/pages\/25084\/revisions\/55738"}],"wp:attachment":[{"href":"https:\/\/tahecosmetics.com\/professional\/pt\/wp-json\/wp\/v2\/media?parent=25084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}